{"id":1320,"date":"2026-02-09T11:56:22","date_gmt":"2026-02-09T11:56:22","guid":{"rendered":"https:\/\/chemicalshoppers.com\/?post_type=product&#038;p=1320"},"modified":"2026-02-13T10:40:05","modified_gmt":"2026-02-13T10:40:05","slug":"fluor-mix-zakje","status":"publish","type":"product","link":"https:\/\/chemicalshoppers.com\/bg\/produkt\/fluor-mix-zakje\/","title":{"rendered":"Fluor mix zakje 1gr"},"content":{"rendered":"<h3 data-start=\"4116\" data-end=\"4137\"><strong data-start=\"4120\" data-end=\"4135\">Introductie<\/strong><\/h3>\n<p data-start=\"4138\" data-end=\"4536\"><strong data-start=\"4138\" data-end=\"4162\">Fluor Mix Zakje (1g)<\/strong> bevat <strong data-start=\"4169\" data-end=\"4222\">1 gram hoogzuivere gefluoreerde onderzoeksstoffen<\/strong>, speciaal ontwikkeld voor <strong data-start=\"4249\" data-end=\"4309\">analytisch, forensisch en chemisch laboratoriumonderzoek<\/strong>. 4 fma<br data-start=\"4310\" data-end=\"4313\" \/>Deze mix bevat <strong data-start=\"4328\" data-end=\"4354\">fluorhoudende analogen<\/strong> van geselecteerde onderzoekssamenstellingen, ideaal voor <strong data-start=\"4412\" data-end=\"4463\">structure-activity relationship (SAR)-onderzoek<\/strong>, <strong data-start=\"4465\" data-end=\"4495\">chromatografische analyses<\/strong> \u0438 <strong data-start=\"4499\" data-end=\"4533\">spectroscopische identificatie<\/strong>.<\/p>\n<p data-start=\"4538\" data-end=\"4856\">Elke batch wordt geproduceerd onder <strong data-start=\"4574\" data-end=\"4619\">gecontroleerde laboratoriumomstandigheden<\/strong> en getest op een <strong data-start=\"4637\" data-end=\"4661\">zuiverheid van \u2265 98%<\/strong>, wat zorgt voor consistente en betrouwbare onderzoeksresultaten.<br data-start=\"4726\" data-end=\"4729\" \/>De mix wordt geleverd in een <strong data-start=\"4758\" data-end=\"4807\">vochtbestendig hersluitbaar laboratoriumzakje<\/strong> voor veilige opslag en langdurige stabiliteit.<\/p>\n<blockquote data-start=\"4858\" data-end=\"5002\">\n<p data-start=\"4860\" data-end=\"5002\">\u26a0\ufe0f <strong data-start=\"4863\" data-end=\"4874\">Let op:<\/strong> Fluor Mix is uitsluitend bedoeld voor <strong data-start=\"4913\" data-end=\"4948\">onderzoek en analytisch gebruik<\/strong> \u2014 <strong data-start=\"4951\" data-end=\"4999\">niet voor menselijke of dierlijke consumptie<\/strong>.<\/p>\n<\/blockquote>\n<hr data-start=\"5004\" data-end=\"5007\" \/>\n<h3 data-start=\"5009\" data-end=\"5040\"><strong data-start=\"5013\" data-end=\"5040\">\u041e\u0441\u043d\u043e\u0432\u043d\u0438 \u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440\u0438\u0441\u0442\u0438\u043a\u0438<\/strong><\/h3>\n<div class=\"_tableContainer_1rjym_1\">\n<div class=\"group _tableWrapper_1rjym_13 flex w-fit flex-col-reverse\" tabindex=\"-1\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"5042\" data-end=\"5582\">\n<thead data-start=\"5042\" data-end=\"5068\">\n<tr data-start=\"5042\" data-end=\"5068\">\n<th data-start=\"5042\" data-end=\"5052\" data-col-size=\"sm\">Kenmerk<\/th>\n<th data-start=\"5052\" data-end=\"5068\" data-col-size=\"md\">Beschrijving<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"5097\" data-end=\"5582\">\n<tr data-start=\"5097\" data-end=\"5128\">\n<td data-start=\"5097\" data-end=\"5115\" data-col-size=\"sm\"><strong data-start=\"5099\" data-end=\"5114\">Productnaam<\/strong><\/td>\n<td data-start=\"5115\" data-end=\"5128\" data-col-size=\"md\">Fluor Mix<\/td>\n<\/tr>\n<tr data-start=\"5129\" data-end=\"5167\">\n<td data-start=\"5129\" data-end=\"5147\" data-col-size=\"sm\"><strong data-start=\"5131\" data-end=\"5146\">\u041a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e<\/strong><\/td>\n<td data-start=\"5147\" data-end=\"5167\" data-col-size=\"md\">1 gram per zakje<\/td>\n<\/tr>\n<tr data-start=\"5168\" data-end=\"5206\">\n<td data-start=\"5168\" data-end=\"5179\" data-col-size=\"sm\"><strong data-start=\"5170\" data-end=\"5178\">Vorm<\/strong><\/td>\n<td data-start=\"5179\" data-end=\"5206\" data-col-size=\"md\">Fijn kristallijn poeder<\/td>\n<\/tr>\n<tr data-start=\"5207\" data-end=\"5260\">\n<td data-start=\"5207\" data-end=\"5224\" data-col-size=\"sm\"><strong data-start=\"5209\" data-end=\"5223\">Zuiverheid<\/strong><\/td>\n<td data-start=\"5224\" data-end=\"5260\" data-col-size=\"md\">\u2265 98% (getest via HPLC en GC\/MS)<\/td>\n<\/tr>\n<tr data-start=\"5261\" data-end=\"5346\">\n<td data-start=\"5261\" data-end=\"5281\" data-col-size=\"sm\"><strong data-start=\"5263\" data-end=\"5280\">Samenstelling<\/strong><\/td>\n<td data-start=\"5281\" data-end=\"5346\" data-col-size=\"md\">Mengsel van gefluoreerde onderzoeksstoffen (batchafhankelijk)<\/td>\n<\/tr>\n<tr data-start=\"5347\" data-end=\"5423\">\n<td data-start=\"5347\" data-end=\"5368\" data-col-size=\"sm\"><strong data-start=\"5349\" data-end=\"5367\">Chemische Type<\/strong><\/td>\n<td data-start=\"5368\" data-end=\"5423\" data-col-size=\"md\">Gefluoreerde analogen \/ analytisch standaardmengsel<\/td>\n<\/tr>\n<tr data-start=\"5424\" data-end=\"5498\">\n<td data-start=\"5424\" data-end=\"5438\" data-col-size=\"sm\"><strong data-start=\"5426\" data-end=\"5437\">Gebruik<\/strong><\/td>\n<td data-start=\"5438\" data-end=\"5498\" data-col-size=\"md\">Alleen voor analytisch, forensisch en chemisch onderzoek<\/td>\n<\/tr>\n<tr data-start=\"5499\" data-end=\"5582\">\n<td data-start=\"5499\" data-end=\"5516\" data-col-size=\"sm\"><strong data-start=\"5501\" data-end=\"5515\">Verpakking<\/strong><\/td>\n<td data-start=\"5516\" data-end=\"5582\" data-col-size=\"md\">Hersluitbaar, antistatisch en vochtbestendig laboratoriumzakje<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<hr data-start=\"5584\" data-end=\"5587\" \/>\n<h3 data-start=\"5589\" data-end=\"5606\"><strong data-start=\"5593\" data-end=\"5606\">\u041f\u0440\u0435\u0434\u0438\u043c\u0441\u0442\u0432\u0430<\/strong><\/h3>\n<ul data-start=\"5608\" data-end=\"6045\">\n<li data-start=\"5608\" data-end=\"5688\">\n<p data-start=\"5610\" data-end=\"5688\"><strong data-start=\"5610\" data-end=\"5629\">Hoge Zuiverheid<\/strong> \u2013 \u2265 98% laboratoriumkwaliteit voor betrouwbare analyses.<\/p>\n<\/li>\n<li data-start=\"5689\" data-end=\"5779\">\n<p data-start=\"5691\" data-end=\"5779\"><strong data-start=\"5691\" data-end=\"5716\">Fluorhoudende Formule<\/strong> \u2013 Bevat zorgvuldig geselecteerde analogen voor vergelijking.<\/p>\n<\/li>\n<li data-start=\"5780\" data-end=\"5875\">\n<p data-start=\"5782\" data-end=\"5875\"><strong data-start=\"5782\" data-end=\"5812\">Breed Onderzoekstoepasbaar<\/strong> \u2013 Geschikt voor chromatografische en spectroscopische tests.<\/p>\n<\/li>\n<li data-start=\"5876\" data-end=\"5968\">\n<p data-start=\"5878\" data-end=\"5968\"><strong data-start=\"5878\" data-end=\"5906\">Gecontroleerde Productie<\/strong> \u2013 Elke batch wordt onder laboratoriumcondities vervaardigd.<\/p>\n<\/li>\n<li data-start=\"5969\" data-end=\"6045\">\n<p data-start=\"5971\" data-end=\"6045\"><strong data-start=\"5971\" data-end=\"5993\">Lange Houdbaarheid<\/strong> \u2013 Verpakking beschermt tegen vocht en degradatie.<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"6047\" data-end=\"6050\" \/>\n<h3 data-start=\"6052\" data-end=\"6104\"><strong data-start=\"6056\" data-end=\"6102\">Gebruik (Alleen voor Onderzoeksdoeleinden)<\/strong><\/h3>\n<ol data-start=\"6106\" data-end=\"6508\">\n<li data-start=\"6106\" data-end=\"6212\">\n<p data-start=\"6109\" data-end=\"6212\"><strong data-start=\"6109\" data-end=\"6124\">Han\u00adtering:<\/strong> Gebruik handschoenen, veiligheidsbril en labjas; werk in een gecontroleerde omgeving.<\/p>\n<\/li>\n<li data-start=\"6213\" data-end=\"6288\">\n<p data-start=\"6216\" data-end=\"6288\"><strong data-start=\"6216\" data-end=\"6229\">Metingen:<\/strong> Gebruik geijkte laboratoriumweegschalen en instrumenten.<\/p>\n<\/li>\n<li data-start=\"6289\" data-end=\"6367\">\n<p data-start=\"6292\" data-end=\"6367\"><strong data-start=\"6292\" data-end=\"6303\">\u0421\u044a\u0445\u0440\u0430\u043d\u0435\u043d\u0438\u0435:<\/strong> Bewaar koel (2\u20138\u00b0C), droog en donker in originele verpakking.<\/p>\n<\/li>\n<li data-start=\"6368\" data-end=\"6432\">\n<p data-start=\"6371\" data-end=\"6432\"><strong data-start=\"6371\" data-end=\"6383\">Analyse:<\/strong> Geschikt voor GC\/MS, LC-MS, HPLC, FTIR en NMR. 4 fma<\/p>\n<\/li>\n<li data-start=\"6433\" data-end=\"6508\">\n<p data-start=\"6436\" data-end=\"6508\"><strong data-start=\"6436\" data-end=\"6453\">\u0414\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u0430\u0446\u0438\u044f:<\/strong> Noteer batchnummers en testresultaten voor naleving.<\/p>\n<\/li>\n<\/ol>\n<hr data-start=\"6510\" data-end=\"6513\" \/>\n<h3 data-start=\"6515\" data-end=\"6550\"><strong data-start=\"6519\" data-end=\"6548\">Veelgestelde Vragen (FAQ)<\/strong><\/h3>\n<p data-start=\"6552\" data-end=\"6689\"><strong data-start=\"6552\" data-end=\"6576\">1. Wat is Fluor Mix?<\/strong><br data-start=\"6576\" data-end=\"6579\" \/><strong data-start=\"6579\" data-end=\"6592\">Fluor Mix<\/strong> \u0435 <strong data-start=\"6600\" data-end=\"6646\">mengsel van gefluoreerde onderzoeksstoffen<\/strong> voor analytisch en forensisch onderzoek.<\/p>\n<p data-start=\"6691\" data-end=\"6829\"><strong data-start=\"6691\" data-end=\"6737\">2. Wat zit er in het Fluor Mix Zakje (1g)?<\/strong><br data-start=\"6737\" data-end=\"6740\" \/>Het zakje bevat <strong data-start=\"6756\" data-end=\"6812\">1 gram hoogzuivere gefluoreerde verbindingen (\u2265 98%)<\/strong> in poedervorm.<\/p>\n<p data-start=\"6831\" data-end=\"7016\"><strong data-start=\"6831\" data-end=\"6874\">3. Is het legaal om Fluor Mix te kopen?<\/strong><br data-start=\"6874\" data-end=\"6877\" \/>\u0421\u0430\u0439\u0442\u044a\u0442 <strong data-start=\"6880\" data-end=\"6908\">legaliteit van Fluor Mix<\/strong> verschilt per land en samenstelling. Controleer altijd de lokale wetgeving voordat u <strong data-start=\"6994\" data-end=\"7013\">Fluor Mix koopt<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Fluorine mix (4-FMA, 2-FMA, 2-FA) sachet with 1 gram<\/span><\/span><\/strong><\/h2>","protected":false},"featured_media":1349,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[468],"product_tag":[90,91,940,22],"class_list":["post-1320","product","type-product","status-publish","has-post-thumbnail","product_cat-b2b","product_tag-4-fma-kopen","product_tag-4-fma","product_tag-fluor-mix-zakje","product_tag-nl","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product\/1320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/comments?post=1320"}],"version-history":[{"count":1,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product\/1320\/revisions"}],"predecessor-version":[{"id":16497,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product\/1320\/revisions\/16497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/media\/1349"}],"wp:attachment":[{"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/media?parent=1320"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product_brand?post=1320"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product_cat?post=1320"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chemicalshoppers.com\/bg\/wp-json\/wp\/v2\/product_tag?post=1320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}